{"id":2991,"date":"2024-11-15T20:00:13","date_gmt":"2024-11-15T19:00:13","guid":{"rendered":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pump-track\/"},"modified":"2025-12-31T13:55:35","modified_gmt":"2025-12-31T12:55:35","slug":"pannonhalma-pump-track","status":"publish","type":"dt_portfolio","link":"https:\/\/northernlinesglobal.com\/en\/projekt\/pannonhalma-pump-track\/","title":{"rendered":"Pannonhalma Pump Track"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-vz-jquery&#8221; bg_image_new=&#8221;id^1504|url^https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp|caption^null|alt^null|title^pannonhalma_pumpapalya_00002|description^null&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(0,0,0,0.82)&#8221; el_class=&#8221;hero-header&#8221;][vc_column width=&#8221;5\/6&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;][vc_column_text css=&#8221;&#8221; el_class=&#8221;after-line-center&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Pannonhalma Pump Track<\/h1>\n<p style=\"text-align: center;\"><strong>Location:<\/strong> Area between the J\u00e1t\u00e9k-V\u00e1r Nursery and Szent Benedek Primary School<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;5\/6&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;][vc_row_inner equal_height=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/4&#8243; offset=&#8221;vc_col-xs-6&#8243;]<div class=\"stats-block stats-top  \"><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\"><\/div><\/div><\/div><div class=\"stats-desc\" id=\"counter-responsv-wrap-8947\"><div id=\"counter_22802837576a97fd5d3a08c\" data-id=\"counter_22802837576a97fd5d3a08c\"  data-ultimate-target='#counter-responsv-wrap-8947 .stats-number'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  class=\"stats-number ult-responsive\" style=\"  \" data-speed=\"3\" data-counter-value=\"344\" data-separator=\".\" data-decimal=\",\">0<\/div><div class=\"counter_suffix mycust ult-responsive\"  data-ultimate-target='#counter-responsv-wrap-8947 .mycust'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  style=\" color:\">m\u00b2<\/div><div id=\"title-counter_22802837576a97fd5d3a08c\"  data-ultimate-target='#counter-responsv-wrap-8947 .stats-text'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"stats-text ult-responsive\" style=\"font-size:18px;  font-weight:bold;\">Asphalted surface<\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; offset=&#8221;vc_col-xs-6&#8243;]<div class=\"stats-block stats-top  \"><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\"><\/div><\/div><\/div><div class=\"stats-desc\" id=\"counter-responsv-wrap-3108\"><div id=\"counter_3064599856a97fd5d3a0d7\" data-id=\"counter_3064599856a97fd5d3a0d7\"  data-ultimate-target='#counter-responsv-wrap-3108 .stats-number'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  class=\"stats-number ult-responsive\" style=\"  \" data-speed=\"4\" data-counter-value=\"132\" data-separator=\".\" data-decimal=\",\">0<\/div><div class=\"counter_suffix mycust ult-responsive\"  data-ultimate-target='#counter-responsv-wrap-3108 .mycust'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  style=\" color:\">m<\/div><div id=\"title-counter_3064599856a97fd5d3a0d7\"  data-ultimate-target='#counter-responsv-wrap-3108 .stats-text'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"stats-text ult-responsive\" style=\"font-size:18px;  font-weight:bold;\">Track length<\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; offset=&#8221;vc_col-xs-6&#8243;]<div class=\"stats-block stats-top  \"><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\"><\/div><\/div><\/div><div class=\"stats-desc\" id=\"counter-responsv-wrap-3412\"><div id=\"counter_26397320496a97fd5d3a10a\" data-id=\"counter_26397320496a97fd5d3a10a\"  data-ultimate-target='#counter-responsv-wrap-3412 .stats-number'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  class=\"stats-number ult-responsive\" style=\"  \" data-speed=\"2\" data-counter-value=\"1\" data-separator=\".\" data-decimal=\",\">0<\/div><div id=\"title-counter_26397320496a97fd5d3a10a\"  data-ultimate-target='#counter-responsv-wrap-3412 .stats-text'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"stats-text ult-responsive\" style=\"font-size:18px;  font-weight:bold;\">Dirt jump element<\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; offset=&#8221;vc_col-xs-6&#8243;]<div class=\"stats-block stats-top  \"><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\"><\/div><\/div><\/div><div class=\"stats-desc\" id=\"counter-responsv-wrap-5049\"><div id=\"counter_12623538936a97fd5d3a137\" data-id=\"counter_12623538936a97fd5d3a137\"  data-ultimate-target='#counter-responsv-wrap-5049 .stats-number'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  class=\"stats-number ult-responsive\" style=\"  \" data-speed=\"3\" data-counter-value=\"1020\" data-separator=\".\" data-decimal=\",\">0<\/div><div class=\"counter_suffix mycust ult-responsive\"  data-ultimate-target='#counter-responsv-wrap-5049 .mycust'  data-responsive-json-new='{\"font-size\":\"desktop:38px;mobile_landscape:30px;\",\"line-height\":\"desktop:46px;mobile_landscape:38px;\"}'  style=\" color:\">m\u00b2<\/div><div id=\"title-counter_12623538936a97fd5d3a137\"  data-ultimate-target='#counter-responsv-wrap-5049 .stats-text'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"stats-text ult-responsive\" style=\"font-size:18px;  font-weight:bold;\">Footprint<\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">#default-btn-49ebecefc539449e4c1974178bc845d3.ico-right-side > i {\n  margin-right: 0px;\n  margin-left: 8px;\n}\n#default-btn-49ebecefc539449e4c1974178bc845d3 > i {\n  margin-right: 8px;\n}<\/style><div class=\"btn-align-center\"><a href=\"#!\/details\" class=\"default-btn-shortcode dt-btn dt-btn-m link-hover-off anchor-link  vc_custom_1767185728929\" id=\"default-btn-49ebecefc539449e4c1974178bc845d3\" title=\"More details\"><span>More details<\/span><\/a><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;one-pager-submenu&#8221;][vc_column]<div class=\"ult_row_spacer\"><div class=\"ult-sticky-anchor\"><div class=\"ult-sticky-section ult-sticky \"  data-gutter= '60' data-stick_behaviour= 'stick_with_scroll'  data-sticky_width= 'fullwidth' data-sticky_position= 'top' data-mobile='no' data-support='no'>[vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li><a class=\"anchor-link\" href=\"#!\/details\">Details<\/a><\/li>\n<li><a class=\"anchor-link\" href=\"#!\/gallery\">Gallery<\/a><\/li>\n<li><a class=\"anchor-link\" href=\"#!\/location\">Location<\/a><\/li>\n<li><a class=\"anchor-link\" href=\"https:\/\/northernlinesglobal.com\/en\/contact-us\/\" target=\"_blank\" rel=\"noopener\">Request a quote<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text]<\/div><div class=\"ult-space\"><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221; el_class=&#8221;p-t-90&#8243; el_id=&#8221;details&#8221;][vc_column el_class=&#8221;order-2&#8243; offset=&#8221;vc_col-sm-offset-0&#8243;][vc_column_text css=&#8221;&#8221; el_class=&#8221;after-line-left&#8221;]<\/p>\n<h2>Features<\/h2>\n<p>Our 2025 season began in Pannonhalma, where we constructed a pump track combined with a dedicated jump line. The facility is located in an impressive setting, directly between a school and a nursery, with a panoramic view of the Pannonhalma Archabbey. Additional service facilities are also being built on site, including lighting, paved walkways, changing rooms, restrooms, and a modern playground \u2014 ensuring that visitors of all ages and skill levels will find suitable recreational opportunities.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1743845955008{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-left-width: 2px !important;padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #CE2B2BB3 !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-radius: 10px !important;border-color: #CE2B2B !important;}&#8221;]<strong>ATTENTION!: Additional construction is currently underway in the pump track area, so use is strictly prohibited and dangerous! The sports facility is expected to open in July 2025.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; el_id=&#8221;reszletek&#8221; el_class=&#8221;p-t-50&#8243;][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221; el_class=&#8221;after-line-left&#8221;]<\/p>\n<h3>Features<\/h3>\n<ul>\n<li>Dedicated dirt jump line with its own routing, featuring <strong>Step-Up<\/strong> and <strong>Step-Down<\/strong> elements<\/li>\n<li>Ideal training environment for both young and adult riders<\/li>\n<li>Impressive location next to a school and nursery<\/li>\n<li>Endless, loopable line combinations with reversible riding direction<\/li>\n<li>Multiple transfer jump opportunities<\/li>\n<li>Three large platforms capable of accommodating a high number of riders<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221; el_class=&#8221;after-line-left&#8221;]<\/p>\n<h3>Specifications<\/h3>\n<ul>\n<li><strong>Asphalted riding surface:<\/strong> 344 m\u00b2<\/li>\n<li><strong>Track length:<\/strong> 132 m<\/li>\n<li><strong>Total sports area dimensions:<\/strong> 30 m \u00d7 34 m<\/li>\n<li>1 dirt jump feature<\/li>\n<li>Step-Up and Step-Down jumps<\/li>\n<li><strong>Footprint:<\/strong> 1020 m\u00b2<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; el_id=&#8221;gallery&#8221; el_class=&#8221;p-b-50&#8243;][vc_column]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 figure,\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 .rollover,\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 img,\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 .gallery-rollover {\n  border-radius: 0px;\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.enable-bg-rollover .gallery-rollover {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.enable-bg-rollover.hover-scale figure .rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n  color: #ffffff;\n}\n.dt-icon-bg-on.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 .gallery-zoom-ico:before,\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 .gallery-zoom-ico span {\n  font-size: 32px;\n  line-height: 44px;\n  color: #ffffff;\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240:not(.resize-by-browser-width) .dt-css-grid {\n  grid-row-gap: 10px;\n  grid-column-gap: 10px;\n  grid-template-columns: repeat(auto-fill,minmax(,1fr));\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240:not(.resize-by-browser-width) .dt-css-grid .double-width {\n  grid-column: span 2;\n}\n.cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240:not(.resize-by-browser-width) .dt-css-grid,\n.no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240:not(.resize-by-browser-width) .dt-css-grid {\n  display: flex;\n  flex-flow: row wrap;\n  margin: -5px;\n}\n.cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240:not(.resize-by-browser-width) .dt-css-grid .wf-cell,\n.no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240:not(.resize-by-browser-width) .dt-css-grid .wf-cell {\n  flex: 1 0 ;\n  max-width: 100%;\n  padding: 5px;\n  box-sizing: border-box;\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid {\n  grid-template-columns: repeat(5,1fr);\n  grid-template-rows: auto;\n  grid-column-gap: 10px;\n  grid-row-gap: 10px;\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .double-width {\n  grid-column: span 2;\n}\n.cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid {\n  margin: -5px;\n}\n.cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell {\n  width: 20%;\n  padding: 5px;\n}\n.cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n  width: calc(20%) * 2;\n}\n.gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width:not(.centered-layout-list):not(.content-bg-on) .dt-css-grid {\n  grid-row-gap: 10px - ;\n}\n@media screen and (max-width: 1199px) {\n  .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(4,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 25%;\n  }\n  .cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(25%)*2;\n  }\n}\n@media screen and (max-width: 991px) {\n  .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(3,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 33.3333333333%;\n  }\n  .cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(33.3333333333%)*2;\n  }\n}\n@media screen and (max-width: 767px) {\n  .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(2,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 50%;\n  }\n  .cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width,\n  .no-cssgridlegacy.no-cssgrid .gallery-shortcode.gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240.resize-by-browser-width .dt-css-grid .wf-cell.double-width {\n    width: calc(50%)*2;\n  }\n}<\/style><div class=\"gallery-shortcode dt-gallery-container gallery-masonry-shortcode-id-36a56f8af9f84b19a4087080b73ca240 mode-masonry jquery-filter dt-icon-bg-off scale-img resize-by-browser-width  hover-fade loading-effect-none description-on-hover\" data-padding=\"5px\" data-cur-page=\"1\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-desktop-columns-num=\"5\" data-v-tablet-columns-num=\"3\" data-h-tablet-columns-num=\"4\" data-phone-columns-num=\"2\" data-width=\"0px\" data-columns=\"0\"><div class=\"iso-container\" ><div class=\"wf-cell iso-item\" data-post-id=\"1927\" data-date=\"2025-04-05T11:34:22+02:00\" data-name=\"pannonhalma_pumpapalya_00001\"><figure class=\"post visible\"><a href=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00001.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1200\" data-large_image_height=\"1600\" data-dt-img-description=\"\" title=\"pannonhalma_pumpapalya_00001\"><img fetchpriority=\"high\" decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20379%20505&#39;%2F%3E\" data-src=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00001-379x505.webp\" data-srcset=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00001-379x505.webp 379w, https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00001-569x758.webp 569w\" loading=\"eager\" style=\"--ratio: 379 \/ 505\" sizes=\"(max-width: 379px) 100vw, 379px\" alt=\"\" width=\"379\" height=\"505\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div class=\"wf-cell iso-item\" data-post-id=\"1928\" data-date=\"2025-04-05T11:34:23+02:00\" data-name=\"pannonhalma_pumpapalya_00002\"><figure class=\"post visible\"><a href=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1600\" data-large_image_height=\"1200\" data-dt-img-description=\"\" title=\"pannonhalma_pumpapalya_00002\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20379%20284&#39;%2F%3E\" data-src=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002-379x284.webp\" data-srcset=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002-379x284.webp 379w, https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002-569x426.webp 569w\" loading=\"eager\" style=\"--ratio: 379 \/ 284\" sizes=\"(max-width: 379px) 100vw, 379px\" alt=\"\" width=\"379\" height=\"284\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div class=\"wf-cell iso-item\" data-post-id=\"1929\" data-date=\"2025-04-05T11:34:24+02:00\" data-name=\"pannonhalma_pumpapalya_00003\"><figure class=\"post visible\"><a href=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00003.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1200\" data-large_image_height=\"1600\" data-dt-img-description=\"\" title=\"pannonhalma_pumpapalya_00003\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20379%20505&#39;%2F%3E\" data-src=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00003-379x505.webp\" data-srcset=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00003-379x505.webp 379w, https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00003-569x758.webp 569w\" loading=\"eager\" style=\"--ratio: 379 \/ 505\" sizes=\"(max-width: 379px) 100vw, 379px\" alt=\"\" width=\"379\" height=\"505\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div class=\"wf-cell iso-item\" data-post-id=\"1930\" data-date=\"2025-04-05T11:34:25+02:00\" data-name=\"pannonhalma_pumpapalya_00004\"><figure class=\"post visible\"><a href=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00004.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1200\" data-large_image_height=\"1600\" data-dt-img-description=\"\" title=\"pannonhalma_pumpapalya_00004\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20379%20505&#39;%2F%3E\" data-src=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00004-379x505.webp\" data-srcset=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00004-379x505.webp 379w, https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00004-569x758.webp 569w\" loading=\"eager\" style=\"--ratio: 379 \/ 505\" sizes=\"(max-width: 379px) 100vw, 379px\" alt=\"\" width=\"379\" height=\"505\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div class=\"wf-cell iso-item\" data-post-id=\"1931\" data-date=\"2025-04-05T11:34:26+02:00\" data-name=\"pannonhalma_pumpapalya_00005\"><figure class=\"post visible\"><a href=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00005.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1600\" data-large_image_height=\"1200\" data-dt-img-description=\"\" title=\"pannonhalma_pumpapalya_00005\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20379%20284&#39;%2F%3E\" data-src=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00005-379x284.webp\" data-srcset=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00005-379x284.webp 379w, https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00005-569x426.webp 569w\" loading=\"eager\" style=\"--ratio: 379 \/ 284\" sizes=\"(max-width: 379px) 100vw, 379px\" alt=\"\" width=\"379\" height=\"284\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><\/div><!-- iso-container|iso-grid --><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_id=&#8221;location&#8221;][vc_column][vc_raw_html css=&#8221;.vc_custom_1743845471716{margin-bottom: -7px !important;}&#8221;]PGlmcmFtZSBzdHlsZT0iYm9yZGVyOiAwOyIgc3JjPSJodHRwczovL3d3dy5nb29nbGUuY29tL21hcHMvZW1iZWQ\/cGI9ITFtMTghMW0xMiExbTMhMWQyMDAzMC43MTc1NTIzMDQ4NCEyZDE3Ljc0MjMwNzM1NTkzODE2ITNkNDcuNTUwOTIyMTAxMzg5MDg0ITJtMyExZjAhMmYwITNmMCEzbTIhMWkxMDI0ITJpNzY4ITRmMTMuMSEzbTMhMW0yITFzMHg0NzZiYzUwMDA5NzgzODkxJTNBMHg1OGYxYzFjY2QyNTE0OWQhMnNQYW5ub25oYWxtYSUyMFB1bXBhcCVDMyVBMWx5YSUyMChOb3J0aGVybiUyMExpbmVzKSE1ZTAhM20yITFzaHUhMnNodSE0djE3NDM4NDU0NTY0ODMhNW0yITFzaHUhMnNodSIgd2lkdGg9IjEwMCUiIGhlaWdodD0iNDUwIiBhbGxvd2Z1bGxzY3JlZW49ImFsbG93ZnVsbHNjcmVlbiI+PC9pZnJhbWU+[\/vc_raw_html][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Location: Area between the J\u00e1t\u00e9k-V\u00e1r Nursery and Szent Benedek Primary School<\/p>\n","protected":false},"author":1,"featured_media":1928,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[34],"dt_portfolio_tags":[],"class_list":["post-2991","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-pump-track","dt_portfolio_category-34","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pannonhalma Pump Track - Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je<\/title>\n<meta name=\"description\" content=\"A safe asphalt pump track in Pannonhalma for all ages \u2013 enjoy biking, skateboarding, or scootering. Free to use!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pannonhalma Pump Track - Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je\" \/>\n<meta property=\"og:description\" content=\"A safe asphalt pump track in Pannonhalma for all ages \u2013 enjoy biking, skateboarding, or scootering. Free to use!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/\" \/>\n<meta property=\"og:site_name\" content=\"Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61552851896736\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-31T12:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/\",\"url\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/\",\"name\":\"Pannonhalma Pump Track - Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je\",\"isPartOf\":{\"@id\":\"http:\/\/northernlinesglobal.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp\",\"datePublished\":\"2024-11-15T19:00:13+00:00\",\"dateModified\":\"2025-12-31T12:55:35+00:00\",\"description\":\"A safe asphalt pump track in Pannonhalma for all ages \u2013 enjoy biking, skateboarding, or scootering. Free to use!\",\"breadcrumb\":{\"@id\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#primaryimage\",\"url\":\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp\",\"contentUrl\":\"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\/\/northernlinesglobal.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/northernlinesglobal.com\/projekt\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pannonhalma Pump Track\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/northernlinesglobal.com\/#website\",\"url\":\"http:\/\/northernlinesglobal.com\/\",\"name\":\"Northern Lines | Aszfalt pumpa \\u2028\u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k \u00e9p\u00edt\u00e9s\u00e9nek, tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je\",\"description\":\"P\u00e1ly\u00e1ink nem csup\u00e1n a versenyz\u0151k sz\u00e1m\u00e1ra ny\u00fajtanak izgalmas kih\u00edv\u00e1sokat, hanem val\u00f3s\u00e1gos k\u00f6z\u00f6ss\u00e9gi k\u00f6zpontok is, ahol a haszn\u00e1lati lehet\u0151s\u00e9gek \u00e9s kih\u00edv\u00e1sok v\u00e9gtelenek.\",\"publisher\":{\"@id\":\"http:\/\/northernlinesglobal.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/northernlinesglobal.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/northernlinesglobal.com\/#organization\",\"name\":\"Northern Lines Kft.\",\"url\":\"http:\/\/northernlinesglobal.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/northernlinesglobal.com\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/northernlinesglobal.com\/wp-content\/uploads\/2024\/02\/northernlines.svg\",\"contentUrl\":\"http:\/\/northernlinesglobal.com\/wp-content\/uploads\/2024\/02\/northernlines.svg\",\"width\":160,\"height\":46,\"caption\":\"Northern Lines Kft.\"},\"image\":{\"@id\":\"http:\/\/northernlinesglobal.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61552851896736\",\"https:\/\/www.instagram.com\/northernlinesglobal\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pannonhalma Pump Track - Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je","description":"A safe asphalt pump track in Pannonhalma for all ages \u2013 enjoy biking, skateboarding, or scootering. Free to use!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/","og_locale":"en_US","og_type":"article","og_title":"Pannonhalma Pump Track - Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je","og_description":"A safe asphalt pump track in Pannonhalma for all ages \u2013 enjoy biking, skateboarding, or scootering. Free to use!","og_url":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/","og_site_name":"Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61552851896736","article_modified_time":"2025-12-31T12:55:35+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/","url":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/","name":"Pannonhalma Pump Track - Northern Lines | Az aszfalt pumpap\u00e1ly\u00e1k \u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je","isPartOf":{"@id":"http:\/\/northernlinesglobal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#primaryimage"},"image":{"@id":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#primaryimage"},"thumbnailUrl":"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp","datePublished":"2024-11-15T19:00:13+00:00","dateModified":"2025-12-31T12:55:35+00:00","description":"A safe asphalt pump track in Pannonhalma for all ages \u2013 enjoy biking, skateboarding, or scootering. Free to use!","breadcrumb":{"@id":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#primaryimage","url":"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp","contentUrl":"https:\/\/northernlinesglobal.com\/wp-content\/uploads\/2025\/04\/pannonhalma_pumpapalya_00002.webp","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/northernlinesglobal.com\/projekt\/pannonhalma-pumpapalya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/northernlinesglobal.com\/en\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/northernlinesglobal.com\/projekt\/"},{"@type":"ListItem","position":3,"name":"Pannonhalma Pump Track"}]},{"@type":"WebSite","@id":"http:\/\/northernlinesglobal.com\/#website","url":"http:\/\/northernlinesglobal.com\/","name":"Northern Lines | Aszfalt pumpa \u2028\u00e9s ker\u00e9kp\u00e1rp\u00e1ly\u00e1k \u00e9p\u00edt\u00e9s\u00e9nek, tervez\u00e9s\u00e9nek \u00e9s kivitelez\u00e9s\u00e9nek szak\u00e9rt\u0151je","description":"P\u00e1ly\u00e1ink nem csup\u00e1n a versenyz\u0151k sz\u00e1m\u00e1ra ny\u00fajtanak izgalmas kih\u00edv\u00e1sokat, hanem val\u00f3s\u00e1gos k\u00f6z\u00f6ss\u00e9gi k\u00f6zpontok is, ahol a haszn\u00e1lati lehet\u0151s\u00e9gek \u00e9s kih\u00edv\u00e1sok v\u00e9gtelenek.","publisher":{"@id":"http:\/\/northernlinesglobal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/northernlinesglobal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/northernlinesglobal.com\/#organization","name":"Northern Lines Kft.","url":"http:\/\/northernlinesglobal.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/northernlinesglobal.com\/#\/schema\/logo\/image\/","url":"http:\/\/northernlinesglobal.com\/wp-content\/uploads\/2024\/02\/northernlines.svg","contentUrl":"http:\/\/northernlinesglobal.com\/wp-content\/uploads\/2024\/02\/northernlines.svg","width":160,"height":46,"caption":"Northern Lines Kft."},"image":{"@id":"http:\/\/northernlinesglobal.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61552851896736","https:\/\/www.instagram.com\/northernlinesglobal\/"]}]}},"_links":{"self":[{"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/dt_portfolio\/2991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/comments?post=2991"}],"version-history":[{"count":3,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/dt_portfolio\/2991\/revisions"}],"predecessor-version":[{"id":2994,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/dt_portfolio\/2991\/revisions\/2994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/media\/1928"}],"wp:attachment":[{"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/media?parent=2991"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/dt_portfolio_category?post=2991"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/northernlinesglobal.com\/en\/wp-json\/wp\/v2\/dt_portfolio_tags?post=2991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}